{"id":5432,"date":"2021-01-23T13:46:11","date_gmt":"2021-01-23T18:46:11","guid":{"rendered":"https:\/\/emendedhearts.com\/?p=5432"},"modified":"2021-12-20T13:17:33","modified_gmt":"2021-12-20T18:17:33","slug":"the-basilisks-creed-chapter-forty-nine-role-play-edition","status":"publish","type":"post","link":"https:\/\/emendedhearts.com\/de\/the-basilisks-creed-chapter-forty-nine-role-play-edition\/","title":{"rendered":"The Basilisk&#039;s Creed: Kapitel Neunundvierzig (Rollenspiel-Edition)"},"content":{"rendered":"<div class=\"swpm-post-not-logged-in-msg\">Sie m\u00fcssen sich anmelden, um diesen Inhalt einsehen zu k\u00f6nnen. Bitte <a class=\"swpm-login-link\" href=\"https:\/\/emendedhearts.com\/member-login\/\">Anmelden<\/a>. Kein Mitglied? <a href=\"https:\/\/emendedhearts.com\/join\/\">Werden Sie Mitglied bei uns<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Sie m\u00fcssen sich anmelden, um diesen Inhalt einsehen zu k\u00f6nnen. Bitte Anmelden. Kein Mitglied? Werden Sie Mitglied bei uns<\/p>","protected":false},"author":2,"featured_media":5325,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[96,106,95],"tags":[],"series":[105],"class_list":["post-5432","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contemporary-2","category-fantasy","category-paranormal","series-the-basilisks-creed-role-play-edition"],"featured_image_src":"https:\/\/emendedhearts.com\/wp-content\/uploads\/2021\/01\/The-Basilisks-Creed-Role-Play-Edition-Cover-Image.jpg","blog_images":{"medium":"https:\/\/emendedhearts.com\/wp-content\/uploads\/2021\/01\/The-Basilisks-Creed-Role-Play-Edition-Cover-Image-300x191.jpg","large":"https:\/\/emendedhearts.com\/wp-content\/uploads\/2021\/01\/The-Basilisks-Creed-Role-Play-Edition-Cover-Image.jpg"},"ams_acf":[],"_links":{"self":[{"href":"https:\/\/emendedhearts.com\/de\/wp-json\/wp\/v2\/posts\/5432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emendedhearts.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/emendedhearts.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/emendedhearts.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/emendedhearts.com\/de\/wp-json\/wp\/v2\/comments?post=5432"}],"version-history":[{"count":0,"href":"https:\/\/emendedhearts.com\/de\/wp-json\/wp\/v2\/posts\/5432\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emendedhearts.com\/de\/wp-json\/wp\/v2\/media\/5325"}],"wp:attachment":[{"href":"https:\/\/emendedhearts.com\/de\/wp-json\/wp\/v2\/media?parent=5432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/emendedhearts.com\/de\/wp-json\/wp\/v2\/categories?post=5432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/emendedhearts.com\/de\/wp-json\/wp\/v2\/tags?post=5432"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/emendedhearts.com\/de\/wp-json\/wp\/v2\/series?post=5432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}