{"id":5720,"date":"2021-02-11T16:39:34","date_gmt":"2021-02-11T21:39:34","guid":{"rendered":"https:\/\/emendedhearts.com\/?p=5720"},"modified":"2021-02-11T16:39:34","modified_gmt":"2021-02-11T21:39:34","slug":"21-questions-chapter-fifty-eight-role-play-edition","status":"publish","type":"post","link":"https:\/\/emendedhearts.com\/fr\/21-questions-chapter-fifty-eight-role-play-edition\/","title":{"rendered":"21 Questions: Chapter Fifty-Eight (Role Play Edition)"},"content":{"rendered":"<div class=\"swpm-post-not-logged-in-msg\">Vous devez \u00eatre connect\u00e9 pour voir ce contenu. Veuillez <a class=\"swpm-login-link\" href=\"https:\/\/emendedhearts.com\/member-login\/\">Rapport<\/a>. Vous n'\u00eates pas membre ? <a href=\"https:\/\/emendedhearts.com\/join\/\">Nous rejoignons<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Vous devez \u00eatre connect\u00e9 pour voir ce contenu. Veuillez Connexion. Vous n&#8217;\u00eates pas membre ? Nous Rejoindre<\/p>","protected":false},"author":2,"featured_media":5484,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[96,93],"tags":[],"series":[107],"class_list":["post-5720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contemporary-2","category-romance","series-21-questions-role-play-edition"],"featured_image_src":"https:\/\/emendedhearts.com\/wp-content\/uploads\/2021\/02\/21-Questions-Role-Play-Edition-Cover-Image-640x1024.jpg","blog_images":{"medium":"https:\/\/emendedhearts.com\/wp-content\/uploads\/2021\/02\/21-Questions-Role-Play-Edition-Cover-Image-188x300.jpg","large":"https:\/\/emendedhearts.com\/wp-content\/uploads\/2021\/02\/21-Questions-Role-Play-Edition-Cover-Image-640x1024.jpg"},"ams_acf":[],"_links":{"self":[{"href":"https:\/\/emendedhearts.com\/fr\/wp-json\/wp\/v2\/posts\/5720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emendedhearts.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/emendedhearts.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/emendedhearts.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/emendedhearts.com\/fr\/wp-json\/wp\/v2\/comments?post=5720"}],"version-history":[{"count":0,"href":"https:\/\/emendedhearts.com\/fr\/wp-json\/wp\/v2\/posts\/5720\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emendedhearts.com\/fr\/wp-json\/wp\/v2\/media\/5484"}],"wp:attachment":[{"href":"https:\/\/emendedhearts.com\/fr\/wp-json\/wp\/v2\/media?parent=5720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/emendedhearts.com\/fr\/wp-json\/wp\/v2\/categories?post=5720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/emendedhearts.com\/fr\/wp-json\/wp\/v2\/tags?post=5720"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/emendedhearts.com\/fr\/wp-json\/wp\/v2\/series?post=5720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}